{"id":605,"date":"2012-05-11T13:14:42","date_gmt":"2012-05-11T13:14:42","guid":{"rendered":"https:\/\/pousadadompedro.com.br\/pousada\/?p=605"},"modified":"2020-12-15T11:52:29","modified_gmt":"2020-12-15T14:52:29","slug":"opiniao-de-clientes","status":"publish","type":"post","link":"https:\/\/pousadadompedro.com.br\/pousada\/opiniao-de-clientes\/","title":{"rendered":"Opini\u00e3o de Clientes"},"content":{"rendered":"[Testimonials]\n<p>Confira abaixo algumas opini\u00f5es de clientes sobre as instala\u00e7\u00f5es, servi\u00e7o e localiza\u00e7\u00e3o da Pousada Dom Pedro.<\/p>\n<p>Veja mais \u00a0opini\u00f5es<a title=\"OPINIOS SOBRE A POUSADA DOM PEDRO\" href=\"https:\/\/www.booking.com\/hotel\/br\/dom-pedro-ii-pousada.pt.html?aid=307415;tab=4;rid=545458325\" target=\"_blank\" rel=\"noopener\">, clicando aqui<\/a>.<\/p>\n<p>J\u00e1 esteve em nossa Pousada Dom Pedro? \u00a0Caso deseje e disponha de uns poucos minutos, \u00a0seremos gratos pelo envio de sua opini\u00e3o ou coment\u00e1rio para que possamos public\u00e1-lo!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Testimonials] Confira abaixo algumas opini\u00f5es de clientes sobre as instala\u00e7\u00f5es, servi\u00e7o e localiza\u00e7\u00e3o da Pousada Dom Pedro. Veja mais \u00a0opini\u00f5es, clicando aqui. J\u00e1 esteve em nossa Pousada Dom Pedro? \u00a0Caso deseje e disponha de uns poucos minutos, \u00a0seremos gratos pelo envio de sua opini\u00e3o ou coment\u00e1rio para que possamos public\u00e1-lo! &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":1027,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"quote","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[29],"tags":[],"class_list":["post-605","post","type-post","status-publish","format-quote","has-post-thumbnail","hentry","category-depoimentos","post_format-post-format-quote"],"_links":{"self":[{"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/posts\/605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/comments?post=605"}],"version-history":[{"count":9,"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/posts\/605\/revisions"}],"predecessor-version":[{"id":1228,"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/posts\/605\/revisions\/1228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/media\/1027"}],"wp:attachment":[{"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/media?parent=605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/categories?post=605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pousadadompedro.com.br\/pousada\/wp-json\/wp\/v2\/tags?post=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}